{"id":5,"count":5,"description":"","link":"http:\/\/trekingeorgia.com\/it\/category\/tours\/trekking\/","name":"Trekking","slug":"trekking","taxonomy":"category","parent":2,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trekking Archives - Trek in Georgia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trekking Archives - Trek in Georgia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/\" \/>\n<meta property=\"og:site_name\" content=\"Trek in Georgia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/\",\"url\":\"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/\",\"name\":\"Trekking Archives - Trek in Georgia\",\"isPartOf\":{\"@id\":\"https:\/\/trekingeorgia.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/trekingeorgia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tours\",\"item\":\"https:\/\/trekingeorgia.com\/category\/tours\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trekking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/trekingeorgia.com\/#website\",\"url\":\"https:\/\/trekingeorgia.com\/\",\"name\":\"Trek in Georgia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/trekingeorgia.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/trekingeorgia.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/trekingeorgia.com\/#organization\",\"name\":\"Trek In Georgia\",\"url\":\"https:\/\/trekingeorgia.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/trekingeorgia.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/trekingeorgia.com\/wp-content\/uploads\/2016\/03\/tig_logo.png\",\"contentUrl\":\"https:\/\/trekingeorgia.com\/wp-content\/uploads\/2016\/03\/tig_logo.png\",\"width\":248,\"height\":110,\"caption\":\"Trek In Georgia\"},\"image\":{\"@id\":\"https:\/\/trekingeorgia.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trekking Archives - Trek in Georgia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/","og_locale":"it_IT","og_type":"article","og_title":"Trekking Archives - Trek in Georgia","og_url":"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/","og_site_name":"Trek in Georgia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/","url":"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/","name":"Trekking Archives - Trek in Georgia","isPartOf":{"@id":"https:\/\/trekingeorgia.com\/#website"},"breadcrumb":{"@id":"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/trekingeorgia.com\/category\/tours\/trekking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trekingeorgia.com\/"},{"@type":"ListItem","position":2,"name":"Tours","item":"https:\/\/trekingeorgia.com\/category\/tours\/"},{"@type":"ListItem","position":3,"name":"Trekking"}]},{"@type":"WebSite","@id":"https:\/\/trekingeorgia.com\/#website","url":"https:\/\/trekingeorgia.com\/","name":"Trek in Georgia","description":"","publisher":{"@id":"https:\/\/trekingeorgia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trekingeorgia.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/trekingeorgia.com\/#organization","name":"Trek In Georgia","url":"https:\/\/trekingeorgia.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/trekingeorgia.com\/#\/schema\/logo\/image\/","url":"https:\/\/trekingeorgia.com\/wp-content\/uploads\/2016\/03\/tig_logo.png","contentUrl":"https:\/\/trekingeorgia.com\/wp-content\/uploads\/2016\/03\/tig_logo.png","width":248,"height":110,"caption":"Trek In Georgia"},"image":{"@id":"https:\/\/trekingeorgia.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/trekingeorgia.com\/it\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/trekingeorgia.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/trekingeorgia.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/trekingeorgia.com\/it\/wp-json\/wp\/v2\/categories\/2"}],"wp:post_type":[{"href":"http:\/\/trekingeorgia.com\/it\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}